{"id":204548,"date":"2026-07-23T10:34:16","date_gmt":"2026-07-23T07:34:16","guid":{"rendered":"https:\/\/astrologelvan.com\/magaza\/?post_type=product&#038;p=204548"},"modified":"2026-08-28T20:24:27","modified_gmt":"2026-08-28T17:24:27","slug":"ay-tasi-ve-obsidyen-bileklik","status":"publish","type":"product","link":"https:\/\/astrologelvan.com\/magaza\/urun\/ay-tasi-ve-obsidyen-bileklik\/","title":{"rendered":"Ay Ta\u015f\u0131 ve Obsidyen \u0130kili Bileklik"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<div><strong>Ay Ta\u015f\u0131,<\/strong> yeni ba\u015flang\u0131\u00e7lar ve d\u00f6n\u00fc\u015f\u00fcm s\u00fcre\u00e7leriyle ili\u015fkilendirilen do\u011fal ta\u015flardan biridir. Spirit\u00fcel inan\u0131\u015flarda sezgi, i\u00e7 ses, sakinlik ve denge temalar\u0131n\u0131 simgeledi\u011fi kabul edilir. Zarif g\u00f6r\u00fcn\u00fcm\u00fc ve ta\u015f\u0131d\u0131\u011f\u0131 sembolik anlamlarla g\u00fcnl\u00fck kullan\u0131m i\u00e7in \u00f6zel bir se\u00e7imdir.<\/div>\n<div><\/div>\n<div><strong>Obsidyen<\/strong> ise geleneksel inan\u0131\u015flarda korunma ve i\u00e7sel fark\u0131ndal\u0131k temalar\u0131yla ili\u015fkilendirilir. Korkular\u0131, g\u00f6lge y\u00f6nleri ve olumsuz d\u00fc\u015f\u00fcnce kal\u0131plar\u0131n\u0131 fark etme niyetini sembolize eder. \u00d6zellikle de\u011fi\u015fim ve d\u00f6n\u00fc\u015f\u00fcm d\u00f6nemlerinde ge\u00e7mi\u015fin y\u00fcklerini geride b\u0131rakma, ki\u015fisel s\u0131n\u0131rlar\u0131 hat\u0131rlama ve i\u00e7sel denge kurma \u00e7al\u0131\u015fmalar\u0131na anlaml\u0131 bir e\u015flik\u00e7i olarak tercih edilir.<\/div>\n<div><\/div>\n<div><strong>Ay Ta\u015f\u0131 ve Obsidyenin<\/strong> sembolik anlamlar\u0131n\u0131 \u00fczerinde ta\u015f\u0131; yeni ba\u015flang\u0131\u00e7lara sezgilerini dinleyerek ad\u0131m atma, ge\u00e7mi\u015fin y\u00fcklerini b\u0131rakma ve ger\u00e7ek potansiyelini ke\u015ffetme niyetini hat\u0131rla. De\u011fi\u015fimi cesaretle kar\u015f\u0131larken i\u00e7sel denge ve korunma sembolizmi sana e\u015flik etsin.<\/div>\n","protected":false},"featured_media":204549,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[596],"product_cat":[258,259],"product_tag":[],"class_list":["post-204548","product","type-product","status-publish","has-post-thumbnail","product_brand-astrolog-elvan","product_cat-bileklik","product_cat-bileklikler","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ay Ta\u015f\u0131 ve Obsidyen \u0130kili Bileklik - Astrolog Elvan<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/astrologelvan.com\/magaza\/urun\/ay-tasi-ve-obsidyen-bileklik\/\" \/>\n<meta property=\"og:locale\" content=\"tr_TR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ay Ta\u015f\u0131 ve Obsidyen \u0130kili Bileklik - Astrolog Elvan\" \/>\n<meta property=\"og:description\" content=\"Ay Ta\u015f\u0131, yeni ba\u015flang\u0131\u00e7lar ve d\u00f6n\u00fc\u015f\u00fcm s\u00fcre\u00e7leriyle ili\u015fkilendirilen do\u011fal ta\u015flardan biridir. Spirit\u00fcel inan\u0131\u015flarda sezgi, i\u00e7 ses, sakinlik ve denge temalar\u0131n\u0131 simgeledi\u011fi kabul edilir. Zarif g\u00f6r\u00fcn\u00fcm\u00fc ve ta\u015f\u0131d\u0131\u011f\u0131 sembolik anlamlarla g\u00fcnl\u00fck kullan\u0131m i\u00e7in \u00f6zel bir se\u00e7imdir.  Obsidyen ise geleneksel inan\u0131\u015flarda korunma ve i\u00e7sel fark\u0131ndal\u0131k temalar\u0131yla ili\u015fkilendirilir. Korkular\u0131, g\u00f6lge y\u00f6nleri ve olumsuz d\u00fc\u015f\u00fcnce kal\u0131plar\u0131n\u0131 fark etme niyetini sembolize eder. \u00d6zellikle de\u011fi\u015fim ve d\u00f6n\u00fc\u015f\u00fcm d\u00f6nemlerinde ge\u00e7mi\u015fin y\u00fcklerini geride b\u0131rakma, ki\u015fisel s\u0131n\u0131rlar\u0131 hat\u0131rlama ve i\u00e7sel denge kurma \u00e7al\u0131\u015fmalar\u0131na anlaml\u0131 bir e\u015flik\u00e7i olarak tercih edilir.  Ay Ta\u015f\u0131 ve Obsidyenin sembolik anlamlar\u0131n\u0131 \u00fczerinde ta\u015f\u0131; yeni ba\u015flang\u0131\u00e7lara sezgilerini dinleyerek ad\u0131m atma, ge\u00e7mi\u015fin y\u00fcklerini b\u0131rakma ve ger\u00e7ek potansiyelini ke\u015ffetme niyetini hat\u0131rla. De\u011fi\u015fimi cesaretle kar\u015f\u0131larken i\u00e7sel denge ve korunma sembolizmi sana e\u015flik etsin.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/astrologelvan.com\/magaza\/urun\/ay-tasi-ve-obsidyen-bileklik\/\" \/>\n<meta property=\"og:site_name\" content=\"Astrolog Elvan\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-28T17:24:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/astrologelvan.com\/magaza\/wp-content\/uploads\/2026\/07\/AYTASI-_OBSIDYEN.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1086\" \/>\n\t<meta property=\"og:image:height\" content=\"1448\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tahmini okuma s\u00fcresi\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 dakika\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/astrologelvan.com\\\/magaza\\\/urun\\\/ay-tasi-ve-obsidyen-bileklik\\\/\",\"url\":\"https:\\\/\\\/astrologelvan.com\\\/magaza\\\/urun\\\/ay-tasi-ve-obsidyen-bileklik\\\/\",\"name\":\"Ay Ta\u015f\u0131 ve Obsidyen \u0130kili Bileklik - Astrolog Elvan\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/astrologelvan.com\\\/magaza\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/astrologelvan.com\\\/magaza\\\/urun\\\/ay-tasi-ve-obsidyen-bileklik\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/astrologelvan.com\\\/magaza\\\/urun\\\/ay-tasi-ve-obsidyen-bileklik\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/astrologelvan.com\\\/magaza\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/AYTASI-_OBSIDYEN.webp\",\"datePublished\":\"2026-07-23T07:34:16+00:00\",\"dateModified\":\"2026-08-28T17:24:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/astrologelvan.com\\\/magaza\\\/urun\\\/ay-tasi-ve-obsidyen-bileklik\\\/#breadcrumb\"},\"inLanguage\":\"tr\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/astrologelvan.com\\\/magaza\\\/urun\\\/ay-tasi-ve-obsidyen-bileklik\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"tr\",\"@id\":\"https:\\\/\\\/astrologelvan.com\\\/magaza\\\/urun\\\/ay-tasi-ve-obsidyen-bileklik\\\/#primaryimage\",\"url\":\"https:\\\/\\\/astrologelvan.com\\\/magaza\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/AYTASI-_OBSIDYEN.webp\",\"contentUrl\":\"https:\\\/\\\/astrologelvan.com\\\/magaza\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/AYTASI-_OBSIDYEN.webp\",\"width\":1086,\"height\":1448},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/astrologelvan.com\\\/magaza\\\/urun\\\/ay-tasi-ve-obsidyen-bileklik\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Anasayfa\",\"item\":\"https:\\\/\\\/astrologelvan.com\\\/magaza\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ma\u011faza\",\"item\":\"https:\\\/\\\/astrologelvan.com\\\/magaza\\\/magaza\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ay Ta\u015f\u0131 ve Obsidyen \u0130kili Bileklik\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/astrologelvan.com\\\/magaza\\\/#website\",\"url\":\"https:\\\/\\\/astrologelvan.com\\\/magaza\\\/\",\"name\":\"Astrolog Elvan\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/astrologelvan.com\\\/magaza\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"tr\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ay Ta\u015f\u0131 ve Obsidyen \u0130kili Bileklik - Astrolog Elvan","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/astrologelvan.com\/magaza\/urun\/ay-tasi-ve-obsidyen-bileklik\/","og_locale":"tr_TR","og_type":"article","og_title":"Ay Ta\u015f\u0131 ve Obsidyen \u0130kili Bileklik - Astrolog Elvan","og_description":"Ay Ta\u015f\u0131, yeni ba\u015flang\u0131\u00e7lar ve d\u00f6n\u00fc\u015f\u00fcm s\u00fcre\u00e7leriyle ili\u015fkilendirilen do\u011fal ta\u015flardan biridir. Spirit\u00fcel inan\u0131\u015flarda sezgi, i\u00e7 ses, sakinlik ve denge temalar\u0131n\u0131 simgeledi\u011fi kabul edilir. Zarif g\u00f6r\u00fcn\u00fcm\u00fc ve ta\u015f\u0131d\u0131\u011f\u0131 sembolik anlamlarla g\u00fcnl\u00fck kullan\u0131m i\u00e7in \u00f6zel bir se\u00e7imdir.  Obsidyen ise geleneksel inan\u0131\u015flarda korunma ve i\u00e7sel fark\u0131ndal\u0131k temalar\u0131yla ili\u015fkilendirilir. Korkular\u0131, g\u00f6lge y\u00f6nleri ve olumsuz d\u00fc\u015f\u00fcnce kal\u0131plar\u0131n\u0131 fark etme niyetini sembolize eder. \u00d6zellikle de\u011fi\u015fim ve d\u00f6n\u00fc\u015f\u00fcm d\u00f6nemlerinde ge\u00e7mi\u015fin y\u00fcklerini geride b\u0131rakma, ki\u015fisel s\u0131n\u0131rlar\u0131 hat\u0131rlama ve i\u00e7sel denge kurma \u00e7al\u0131\u015fmalar\u0131na anlaml\u0131 bir e\u015flik\u00e7i olarak tercih edilir.  Ay Ta\u015f\u0131 ve Obsidyenin sembolik anlamlar\u0131n\u0131 \u00fczerinde ta\u015f\u0131; yeni ba\u015flang\u0131\u00e7lara sezgilerini dinleyerek ad\u0131m atma, ge\u00e7mi\u015fin y\u00fcklerini b\u0131rakma ve ger\u00e7ek potansiyelini ke\u015ffetme niyetini hat\u0131rla. De\u011fi\u015fimi cesaretle kar\u015f\u0131larken i\u00e7sel denge ve korunma sembolizmi sana e\u015flik etsin.","og_url":"https:\/\/astrologelvan.com\/magaza\/urun\/ay-tasi-ve-obsidyen-bileklik\/","og_site_name":"Astrolog Elvan","article_modified_time":"2026-08-28T17:24:27+00:00","og_image":[{"width":1086,"height":1448,"url":"https:\/\/astrologelvan.com\/magaza\/wp-content\/uploads\/2026\/07\/AYTASI-_OBSIDYEN.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Tahmini okuma s\u00fcresi":"1 dakika"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/astrologelvan.com\/magaza\/urun\/ay-tasi-ve-obsidyen-bileklik\/","url":"https:\/\/astrologelvan.com\/magaza\/urun\/ay-tasi-ve-obsidyen-bileklik\/","name":"Ay Ta\u015f\u0131 ve Obsidyen \u0130kili Bileklik - Astrolog Elvan","isPartOf":{"@id":"https:\/\/astrologelvan.com\/magaza\/#website"},"primaryImageOfPage":{"@id":"https:\/\/astrologelvan.com\/magaza\/urun\/ay-tasi-ve-obsidyen-bileklik\/#primaryimage"},"image":{"@id":"https:\/\/astrologelvan.com\/magaza\/urun\/ay-tasi-ve-obsidyen-bileklik\/#primaryimage"},"thumbnailUrl":"https:\/\/astrologelvan.com\/magaza\/wp-content\/uploads\/2026\/07\/AYTASI-_OBSIDYEN.webp","datePublished":"2026-07-23T07:34:16+00:00","dateModified":"2026-08-28T17:24:27+00:00","breadcrumb":{"@id":"https:\/\/astrologelvan.com\/magaza\/urun\/ay-tasi-ve-obsidyen-bileklik\/#breadcrumb"},"inLanguage":"tr","potentialAction":[{"@type":"ReadAction","target":["https:\/\/astrologelvan.com\/magaza\/urun\/ay-tasi-ve-obsidyen-bileklik\/"]}]},{"@type":"ImageObject","inLanguage":"tr","@id":"https:\/\/astrologelvan.com\/magaza\/urun\/ay-tasi-ve-obsidyen-bileklik\/#primaryimage","url":"https:\/\/astrologelvan.com\/magaza\/wp-content\/uploads\/2026\/07\/AYTASI-_OBSIDYEN.webp","contentUrl":"https:\/\/astrologelvan.com\/magaza\/wp-content\/uploads\/2026\/07\/AYTASI-_OBSIDYEN.webp","width":1086,"height":1448},{"@type":"BreadcrumbList","@id":"https:\/\/astrologelvan.com\/magaza\/urun\/ay-tasi-ve-obsidyen-bileklik\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Anasayfa","item":"https:\/\/astrologelvan.com\/magaza\/"},{"@type":"ListItem","position":2,"name":"Ma\u011faza","item":"https:\/\/astrologelvan.com\/magaza\/magaza\/"},{"@type":"ListItem","position":3,"name":"Ay Ta\u015f\u0131 ve Obsidyen \u0130kili Bileklik"}]},{"@type":"WebSite","@id":"https:\/\/astrologelvan.com\/magaza\/#website","url":"https:\/\/astrologelvan.com\/magaza\/","name":"Astrolog Elvan","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/astrologelvan.com\/magaza\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"tr"}]}},"_links":{"self":[{"href":"https:\/\/astrologelvan.com\/magaza\/wp-json\/wp\/v2\/product\/204548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/astrologelvan.com\/magaza\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/astrologelvan.com\/magaza\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/astrologelvan.com\/magaza\/wp-json\/wp\/v2\/comments?post=204548"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/astrologelvan.com\/magaza\/wp-json\/wp\/v2\/media\/204549"}],"wp:attachment":[{"href":"https:\/\/astrologelvan.com\/magaza\/wp-json\/wp\/v2\/media?parent=204548"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/astrologelvan.com\/magaza\/wp-json\/wp\/v2\/product_brand?post=204548"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/astrologelvan.com\/magaza\/wp-json\/wp\/v2\/product_cat?post=204548"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/astrologelvan.com\/magaza\/wp-json\/wp\/v2\/product_tag?post=204548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}